{"id":5884,"date":"2025-02-03T10:12:35","date_gmt":"2025-02-03T10:12:35","guid":{"rendered":"https:\/\/www.mutualitats.cat\/?p=5884"},"modified":"2025-05-07T06:44:58","modified_gmt":"2025-05-07T06:44:58","slug":"descubre-exclusivas-entrevistas-11o-encuentro","status":"publish","type":"post","link":"https:\/\/www.mutualitats.cat\/es\/descubre-exclusivas-entrevistas-11o-encuentro\/","title":{"rendered":"Descubre las exclusivas entrevistas del 11\u00ba encuentro"},"content":{"rendered":"\n<p class=\"has-small-font-size\">Durante el 11\u00ba Encuentro de las Mutualidades de Catalu\u00f1a, la Federaci\u00f3n registr\u00f3 diversas <a href=\"https:\/\/www.youtube.com\/playlist?list=PLGLLMUIum55pumhon3NJaeqSmDYgEeShs\">entrevistas<\/a> con el objetivo de profundizar en la informaci\u00f3n sobre el evento. Estas recogen los puntos de vista de miembros de la entidad, ponentes e incluso representantes de las diferentes mutualidades, ofreciendo un amplio abanico de perspectivas.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Tem\u00e1ticas como el funcionamiento de la organizaci\u00f3n, la utilidad de los encuentros y la necesidad constante de formaci\u00f3n son tratadas en estos v\u00eddeos, as\u00ed como tambi\u00e9n se encuentran consejos sobre estrategia, liderazgo e innovaci\u00f3n del sector asegurador. Estas entrevistas <strong>revelan una parte hasta ahora desconocida del encuentro y permiten conocer de cerca las ideas y experiencias compartidas durante el evento<\/strong>.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Actualmente, estas grabaciones ya est\u00e1n disponibles en el canal de Youtube de la Federaci\u00f3n, donde cualquier persona interesada puede acceder. Estos v\u00eddeos ofrecen una visi\u00f3n privilegiada de las aportaciones realizadas en el marco del 11\u00ba Encuentro de las Mutualidades de Catalu\u00f1a y <strong>ponen al alcance de todos los conocimientos m\u00e1s valiosos sobre el sector mutualista<\/strong>. Es por eso que, desde la Federaci\u00f3n, te animamos a explorar este contenido exclusivo, que seguro te aportar\u00e1 inspiraci\u00f3n y herramientas pr\u00e1cticas.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"11\u00aa Trobada de Mutualitats de Catalunya\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/videoseries?list=PLGLLMUIum55pumhon3NJaeqSmDYgEeShs\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Durante el 11\u00ba Encuentro de las Mutualidades de Catalu\u00f1a, la Federaci\u00f3n registr\u00f3 diversas entrevistas con el objetivo de profundizar en la informaci\u00f3n sobre el evento. Estas recogen los puntos de vista de miembros de la entidad, ponentes e incluso representantes de las diferentes mutualidades, ofreciendo un amplio abanico de perspectivas. Tem\u00e1ticas como el funcionamiento de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69],"tags":[],"class_list":["post-5884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/posts\/5884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/comments?post=5884"}],"version-history":[{"count":4,"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/posts\/5884\/revisions"}],"predecessor-version":[{"id":5888,"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/posts\/5884\/revisions\/5888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/media\/5877"}],"wp:attachment":[{"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/media?parent=5884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/categories?post=5884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mutualitats.cat\/es\/wp-json\/wp\/v2\/tags?post=5884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}